{"id":6763,"date":"2025-05-12T21:08:08","date_gmt":"2025-05-13T03:08:08","guid":{"rendered":"https:\/\/agencia.252.com.mx\/home\/?p=6763"},"modified":"2025-05-12T21:08:09","modified_gmt":"2025-05-13T03:08:09","slug":"las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/","title":{"rendered":"Las y los Naucalpenses aprueban el trabajo de Issac Montoya"},"content":{"rendered":"<p>Visitas: 89<\/p>\n<ul class=\"wp-block-list\">\n<li><em>Encuesta de Consulta Mitofsky, coloca al alcalde de Naucalpan con el mayor incremento en la aprobaci\u00f3n ciudadana, m\u00e1s de 10 puntos del primero al segundo bimestre.<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u2060<\/em><em>El alcalde, en los primeros 120 d\u00edas de administraci\u00f3n inform\u00f3 a la ciudadan\u00eda de avances significativos y estructurales en obras y servicios p\u00fablicos, as\u00ed como en seguridad, entre otros rubros.<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><em>Naucalpan, Estado de M\u00e9xico, a 12 de mayo de 2025<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cuatro meses de gobierno, con avances significativos y estructurales en obras y servicios p\u00fablicos, as\u00ed como en seguridad, atenci\u00f3n a la ciudadan\u00eda, entre otros rubros, el presidente municipal, Isaac Montoya M\u00e1rquez, se coloc\u00f3 como el alcalde con el mayor incremento en la aprobaci\u00f3n ciudadana, del primero al segundo bimestre con m\u00e1s de 10 puntos, de acuerdo a una encuesta de Consulta Mitofsky.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados que presenta la encuesta de Mitofsky, registran que, en el mes de febrero, el alcalde naucalpense ten\u00eda un nivel de aprobaci\u00f3n del 36.6% y para abril registr\u00f3 un incremento de m\u00e1s del 10%, para alcanzar el 47.1% y ubicarse en el primer lugar de aprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a este ranking bimestral de Mitofsky, de los alcaldes del pa\u00eds que mejoraron su aprobaci\u00f3n, el presidente municipal de Naucalpan se coloc\u00f3 a la cabeza. Esta encuesta bimestral ciudadana fue levantada para un medio nacional (El Economista), en la que se consider\u00f3 a 150 presidentas y presidentes municipales a nivel nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, el alcalde de Naucalpan, recientemente present\u00f3 resultados a las y los naucalpenses a 120 d\u00edas de gobierno, inform\u00f3 que, en obra p\u00fablica, se invertir\u00e1n 700 millones de pesos, en el primer a\u00f1o de gobierno. Y se trabajar\u00e1 por la rehabilitaci\u00f3n de 1 mill\u00f3n de m\u00b2 de calles y avenidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apenas a cuatro meses, ya se avanza en la rehabilitaci\u00f3n calles y avenidas como Minas Palacio, Estacas, Diagonal Centenario, Ramos Mill\u00e1n, El Chamizal, entre otras.&nbsp; De esta manera la ciudadan\u00eda tiene la certeza de que los recursos llegan a las obras m\u00e1s necesarias en sus comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, como parte de la estrategia Seguridad con Todo, que impulsa el gobierno de Montoya M\u00e1rquez, se dio la transici\u00f3n de la Polic\u00eda Municipal a Guardia Municipal, corporaci\u00f3n que ser\u00e1 de proximidad en todas las comunidades y que reforzar\u00e1 sus acciones con 250 nuevas patrullas, as\u00ed como con drones t\u00e1cticos, radios duales, c\u00e1maras con GPS, entre otro equipamiento, para recuperar la paz y tranquilidad de las y los naucalpenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, a cuatro meses de gobierno, disminuye la percepci\u00f3n de inseguridad en Naucalpan, al primer trimestre del 2025, bajamos del lugar 2 hasta el 12, de acuerdo a la ENSU. Y a fin de disminuir la incidencia delictiva se han realizado m\u00e1s de 600 operativos de manera coordinada con los tres \u00f3rdenes de gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La administraci\u00f3n que encabeza Isaac Montoya, ha destinado una inversi\u00f3n de 113 millones de pesos a infraestructura hidr\u00e1ulica, durante este primer a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunado a ello, el gobierno municipal, a trav\u00e9s del Organismo del Agua Municipal OAPAS, trabaja de manera preventiva y coordinada con la CONAGUA a trav\u00e9s del OCAVM, en el desfogue de la Presa Los Cuartos para extracci\u00f3n de tap\u00f3n de basura a 100 metros de profundidad y se han retirado m\u00e1s 500 camiones de basura de la presa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, el gobierno municipal reitera su compromiso por la transformaci\u00f3n de las comunidades de Naucalpan, e impulsa diversos programas y acciones, tambi\u00e9n en servicios p\u00fablicos, bienestar social, desarrollo urbano, medio ambiente y bienestar animal, entre otros rubros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 89 Naucalpan, Estado de M\u00e9xico, a 12 de mayo de 2025 A cuatro meses de gobierno, con avances significativos y estructurales en obras y servicios p\u00fablicos, as\u00ed como en seguridad, atenci\u00f3n a la ciudadan\u00eda, entre otros rubros, el presidente municipal, Isaac Montoya M\u00e1rquez, se coloc\u00f3 como el alcalde con el mayor incremento en la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8,70],"tags":[526],"class_list":["post-6763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edomex","category-naucalpan","tag-edomex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las y los Naucalpenses aprueban el trabajo de Issac Montoya - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las y los Naucalpenses aprueban el trabajo de Issac Montoya - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 89 Naucalpan, Estado de M\u00e9xico, a 12 de mayo de 2025 A cuatro meses de gobierno, con avances significativos y estructurales en obras y servicios p\u00fablicos, as\u00ed como en seguridad, atenci\u00f3n a la ciudadan\u00eda, entre otros rubros, el presidente municipal, Isaac Montoya M\u00e1rquez, se coloc\u00f3 como el alcalde con el mayor incremento en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jcorroherrera\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-13T03:08:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T03:08:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"733\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Corro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Juan Ignacio Corro Herrera\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Corro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/\"},\"author\":{\"name\":\"Nacho Corro\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\"},\"headline\":\"Las y los Naucalpenses aprueban el trabajo de Issac Montoya\",\"datePublished\":\"2025-05-13T03:08:08+00:00\",\"dateModified\":\"2025-05-13T03:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg\",\"keywords\":[\"Edomex\"],\"articleSection\":[\"Edomex\",\"Naucalpan\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/\",\"name\":\"Las y los Naucalpenses aprueban el trabajo de Issac Montoya - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg\",\"datePublished\":\"2025-05-13T03:08:08+00:00\",\"dateModified\":\"2025-05-13T03:08:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg\",\"width\":733,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las y los Naucalpenses aprueban el trabajo de Issac Montoya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\",\"name\":\"Nacho Corro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"caption\":\"Nacho Corro\"},\"description\":\"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jcorroherrera\\\/\",\"www.instagram.com\\\/nachocorro\\\/\",\"https:\\\/\\\/x.com\\\/Juan Ignacio Corro Herrera\"],\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/i-corro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las y los Naucalpenses aprueban el trabajo de Issac Montoya - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/","og_locale":"es_ES","og_type":"article","og_title":"Las y los Naucalpenses aprueban el trabajo de Issac Montoya - Agencia252","og_description":"Visitas: 89 Naucalpan, Estado de M\u00e9xico, a 12 de mayo de 2025 A cuatro meses de gobierno, con avances significativos y estructurales en obras y servicios p\u00fablicos, as\u00ed como en seguridad, atenci\u00f3n a la ciudadan\u00eda, entre otros rubros, el presidente municipal, Isaac Montoya M\u00e1rquez, se coloc\u00f3 como el alcalde con el mayor incremento en la [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_author":"https:\/\/www.facebook.com\/jcorroherrera\/","article_published_time":"2025-05-13T03:08:08+00:00","article_modified_time":"2025-05-13T03:08:09+00:00","og_image":[{"width":733,"height":1280,"url":"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg","type":"image\/jpeg"}],"author":"Nacho Corro","twitter_card":"summary_large_image","twitter_creator":"@Juan Ignacio Corro Herrera","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"Nacho Corro","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/"},"author":{"name":"Nacho Corro","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098"},"headline":"Las y los Naucalpenses aprueban el trabajo de Issac Montoya","datePublished":"2025-05-13T03:08:08+00:00","dateModified":"2025-05-13T03:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg","keywords":["Edomex"],"articleSection":["Edomex","Naucalpan"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/","url":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/","name":"Las y los Naucalpenses aprueban el trabajo de Issac Montoya - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg","datePublished":"2025-05-13T03:08:08+00:00","dateModified":"2025-05-13T03:08:09+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#primaryimage","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-12-at-3.10.37-PM.jpeg","width":733,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/las-y-los-naucalpenses-aprueban-el-trabajo-de-issac-montoya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Las y los Naucalpenses aprueban el trabajo de Issac Montoya"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098","name":"Nacho Corro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","caption":"Nacho Corro"},"description":"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda","sameAs":["https:\/\/www.facebook.com\/jcorroherrera\/","www.instagram.com\/nachocorro\/","https:\/\/x.com\/Juan Ignacio Corro Herrera"],"url":"https:\/\/agencia.252.com.mx\/home\/author\/i-corro\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/6763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=6763"}],"version-history":[{"count":1,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/6763\/revisions"}],"predecessor-version":[{"id":6765,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/6763\/revisions\/6765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media\/6764"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=6763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=6763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=6763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}