{"id":406,"date":"2020-03-06T15:46:00","date_gmt":"2020-03-06T21:46:00","guid":{"rendered":"http:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/"},"modified":"2020-03-06T15:46:00","modified_gmt":"2020-03-06T21:46:00","slug":"le-quedaron-grandes-los-zapatos-a-maribel-cervantes","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/","title":{"rendered":"Le quedaron grandes los zapatos a Maribel Cervantes"},"content":{"rendered":"<p>Visitas: 60<\/p><div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><\/div>\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s1600\/zapatotes.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" data-original-height=\"770\" data-original-width=\"1175\" height=\"209\" src=\"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg\" width=\"320\" \/><\/a><\/div>\n<p><\/p>\n<div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><\/div>\n<div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><\/div>\n<div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><span style=\"font-family: &quot;arial&quot; , sans-serif;\">Por Juan Insomnio <o:p><\/o:p><\/span><\/div>\n<div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><\/div>\n<div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><span style=\"font-family: &quot;arial&quot; , sans-serif;\">Estado de M\u00e9xico a 5 de marzo del 2020.- Literal, a la Secretaria de Seguridad del Estado de M\u00e9xico le quedaron grandes los zapatos, y no nada m\u00e1s los que usa en eventos, sino en los nulos resultados que la Polic\u00eda Estatal a su cargo con sus diversas divisiones no han podido frenar una delincuencia que opera a la sombra de los intereses de la corrupci\u00f3n que impera en la corporaci\u00f3n.<\/span><\/div>\n<p><a name='more'><\/a><o:p><\/o:p><\/p>\n<div style=\"line-height: normal; margin-bottom: .0001pt; margin-bottom: 0cm; mso-layout-grid-align: none; mso-pagination: none; tab-stops: 36.0pt 72.0pt 108.0pt 144.0pt 180.0pt 216.0pt 252.0pt 288.0pt 324.0pt 360.0pt 396.0pt 432.0pt; text-align: justify; text-autospace: none; text-justify: inter-ideograph;\"><\/div>\n<p><span style=\"font-family: &quot;verdana&quot; , sans-serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: &quot;verdana&quot; , sans-serif;\">La semana pasada el triple homicidio cometido por un grupo armado en las inmediaciones de Bulevares y San Mateo en Naucalpan, fortalec\u00edan las declaraciones del escritor Francisco Cruz quien se\u00f1alaba ante Carmen Aristegi los nulos trabajos de efectividad policial que tiene el Gobierno Estatal en materia de seguridad p\u00fablica.<\/span><\/div>\n<p><span style=\"font-family: &quot;verdana&quot; , sans-serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: &quot;verdana&quot; , sans-serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: &quot;verdana&quot; , sans-serif;\"><\/p>\n<div style=\"text-align: justify;\">A las pocas horas, el video de un chofer de tr\u00e1iler extorsionado por el Jefe de Servicios del Primer Agrupamiento de la Polic\u00eda Estatal, Miguel \u00c1guila Julio, evidenciaba que la corrupci\u00f3n esta incrustada en la corporaci\u00f3n a mas no poder, el mando medio opt\u00f3 por renunciar en cuanto se enter\u00f3 del video, fue la salida m\u00e1s sencilla para \u00e9l y evitar un proceso de investigaci\u00f3n y caer en la c\u00e1rcel.&nbsp;<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La renta de patrullas y personal a empresarios para cuidar sus negocios es m\u00e1s cada d\u00eda, ah\u00ed es donde los mandos policiales obtienen hasta triples ganancias, el primero el cobro que le hacen al empresario por brindarle el \u201capoyo\u201d que una patrulla se estacione por horas y el personal con mejor armamento y capacitaci\u00f3n que uno de seguridad privada permanezca en el local comercial durante su operaci\u00f3n.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Segundo, la gasolina de esas patrullas que No salen a realizar su labor p\u00fablica, se \u201ccobra por aparte\u201d y entra directamente al bolsillo de los mandos, ya que todos los veh\u00edculos para no levantar sospechas deben de acudir diariamente por su dotaci\u00f3n de combustible.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Tercero, la mejor conocida \u201cFuerza a\u00e9rea o aviadores\u201d, polic\u00edas que a cambio de la mitad de su salario que entregan a los mandos por no ir a trabajar, ya que el sueldo es bajo y el riesgo alto, prefieren perder una quincena y trabajar en otras labores sin poner en riesgo sus prestaciones m\u00e9dicas, aguinaldo, vacaciones, de ah\u00ed que por m\u00e1s discursos en materia de seguridad, los resultados sean inexistentes.<\/div>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 60 Por Juan Insomnio Estado de M\u00e9xico a 5 de marzo del 2020.- Literal, a la Secretaria de Seguridad del Estado de M\u00e9xico le quedaron grandes los zapatos, y no nada m\u00e1s los que usa en eventos, sino en los nulos resultados que la Polic\u00eda Estatal a su cargo con sus diversas divisiones no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[247,8],"tags":[],"class_list":["post-406","post","type-post","status-publish","format-standard","hentry","category-columna","category-edomex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le quedaron grandes los zapatos a Maribel Cervantes - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le quedaron grandes los zapatos a Maribel Cervantes - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 60 Por Juan Insomnio Estado de M\u00e9xico a 5 de marzo del 2020.- Literal, a la Secretaria de Seguridad del Estado de M\u00e9xico le quedaron grandes los zapatos, y no nada m\u00e1s los que usa en eventos, sino en los nulos resultados que la Polic\u00eda Estatal a su cargo con sus diversas divisiones no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T21:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg\" \/>\n<meta name=\"author\" content=\"C\u00e9sar D\u00edaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@252COMS\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9sar D\u00edaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/\"},\"author\":{\"name\":\"C\u00e9sar D\u00edaz\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/5b572a97d324685fe6ca87bd627de79a\"},\"headline\":\"Le quedaron grandes los zapatos a Maribel Cervantes\",\"datePublished\":\"2020-03-06T21:46:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-QEr1H9HWeog\\\/XmCn2rJS7gI\\\/AAAAAAAAElY\\\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\\\/s320\\\/zapatotes.jpg\",\"articleSection\":[\"columna\",\"Edomex\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/\",\"name\":\"Le quedaron grandes los zapatos a Maribel Cervantes - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-QEr1H9HWeog\\\/XmCn2rJS7gI\\\/AAAAAAAAElY\\\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\\\/s320\\\/zapatotes.jpg\",\"datePublished\":\"2020-03-06T21:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-QEr1H9HWeog\\\/XmCn2rJS7gI\\\/AAAAAAAAElY\\\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\\\/s320\\\/zapatotes.jpg\",\"contentUrl\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-QEr1H9HWeog\\\/XmCn2rJS7gI\\\/AAAAAAAAElY\\\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\\\/s320\\\/zapatotes.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le quedaron grandes los zapatos a Maribel Cervantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/5b572a97d324685fe6ca87bd627de79a\",\"name\":\"C\u00e9sar D\u00edaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8f76667be0aa9874637720ae3e7c0d5db56e69308e4263058f4c756f1573081?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8f76667be0aa9874637720ae3e7c0d5db56e69308e4263058f4c756f1573081?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8f76667be0aa9874637720ae3e7c0d5db56e69308e4263058f4c756f1573081?s=96&r=g\",\"caption\":\"C\u00e9sar D\u00edaz\"},\"description\":\"Fotoperiodista independiente\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/252cm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le quedaron grandes los zapatos a Maribel Cervantes - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/","og_locale":"es_ES","og_type":"article","og_title":"Le quedaron grandes los zapatos a Maribel Cervantes - Agencia252","og_description":"Visitas: 60 Por Juan Insomnio Estado de M\u00e9xico a 5 de marzo del 2020.- Literal, a la Secretaria de Seguridad del Estado de M\u00e9xico le quedaron grandes los zapatos, y no nada m\u00e1s los que usa en eventos, sino en los nulos resultados que la Polic\u00eda Estatal a su cargo con sus diversas divisiones no [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_published_time":"2020-03-06T21:46:00+00:00","og_image":[{"url":"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg","type":"","width":"","height":""}],"author":"C\u00e9sar D\u00edaz","twitter_card":"summary_large_image","twitter_creator":"@252COMS","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"C\u00e9sar D\u00edaz","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/"},"author":{"name":"C\u00e9sar D\u00edaz","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/5b572a97d324685fe6ca87bd627de79a"},"headline":"Le quedaron grandes los zapatos a Maribel Cervantes","datePublished":"2020-03-06T21:46:00+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#primaryimage"},"thumbnailUrl":"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg","articleSection":["columna","Edomex"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/","url":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/","name":"Le quedaron grandes los zapatos a Maribel Cervantes - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#primaryimage"},"thumbnailUrl":"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg","datePublished":"2020-03-06T21:46:00+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#primaryimage","url":"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg","contentUrl":"https:\/\/1.bp.blogspot.com\/-QEr1H9HWeog\/XmCn2rJS7gI\/AAAAAAAAElY\/jvKFO1q2kMk-PD-hXwsOu4yS0hEXObVXQCLcBGAsYHQ\/s320\/zapatotes.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/le-quedaron-grandes-los-zapatos-a-maribel-cervantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Le quedaron grandes los zapatos a Maribel Cervantes"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/5b572a97d324685fe6ca87bd627de79a","name":"C\u00e9sar D\u00edaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b8f76667be0aa9874637720ae3e7c0d5db56e69308e4263058f4c756f1573081?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b8f76667be0aa9874637720ae3e7c0d5db56e69308e4263058f4c756f1573081?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8f76667be0aa9874637720ae3e7c0d5db56e69308e4263058f4c756f1573081?s=96&r=g","caption":"C\u00e9sar D\u00edaz"},"description":"Fotoperiodista independiente","url":"https:\/\/agencia.252.com.mx\/home\/author\/252cm\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=406"}],"version-history":[{"count":0,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/406\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}