{"id":21480,"date":"2026-07-15T10:11:42","date_gmt":"2026-07-15T16:11:42","guid":{"rendered":"https:\/\/agencia.252.com.mx\/home\/?p=21480"},"modified":"2026-07-15T10:11:51","modified_gmt":"2026-07-15T16:11:51","slug":"reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/","title":{"rendered":"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0"},"content":{"rendered":"<p>Visitas: 3<\/p>\n<ul class=\"wp-block-list\">\n<li><em>Raciel P\u00e9rez Cruz, entreg\u00f3 las instalaciones renovadas del CECI \u201cMadre Teresa de Calcuta\u201d en su nueva sede, como parte del cumplimiento de los compromisos asumidos en el Pacto por la Primera Infancia.<\/em><\/li>\n\n\n\n<li><em>Las nuevas instalaciones optimizan la infraestructura p\u00fablica para garantizar entornos m\u00e1s dignos, funcionales, seguros y supervisados bajo las normas de protecci\u00f3n civil en beneficio de la ni\u00f1ez de la demarcaci\u00f3n.<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Ignacio Corro&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Tlalnepantla, Estado de M\u00e9xico, a 15 de julio de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Presidente Municipal de Tlalnepantla, Raciel P\u00e9rez Cruz, encabez\u00f3 la entrega de las instalaciones renovadas y la develaci\u00f3n de la placa conmemorativa de la reapertura del Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calcuta\u201d, el cual estrena sede en la calle Periodistas sin n\u00famero, en la colonia Prensa Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta acci\u00f3n representa una medida concreta derivada de la firma del Pacto por la Primera Infancia que el edil formaliz\u00f3 al inicio de su gesti\u00f3n, lo que reafirma el compromiso de la administraci\u00f3n local con el bienestar, protecci\u00f3n y desarrollo de la ni\u00f1ez del municipio, optimiza la infraestructura p\u00fablica para garantizar entornos m\u00e1s dignos, funcionales, seguros y supervisados bajo las normas de protecci\u00f3n civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abInvertir en la primera infancia no es solamente mejorar instalaciones. Es construir bienestar, prevenir desigualdades y generar mejores oportunidades para el futuro. Lo que hagamos hoy por nuestras ni\u00f1as y nuestros ni\u00f1os tendr\u00e1 efectos en toda su vida y en el desarrollo de nuestro municipio\u00bb, manifest\u00f3 el alcalde Raciel P\u00e9rez Cruz durante su intervenci\u00f3n en la ceremonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades municipales destacaron que la reubicaci\u00f3n a un costado de la Unidad de Salud de Primer Nivel Prensa Nacional de IMSS-Bienestar facilitar\u00e1 la creaci\u00f3n de redes institucionales permanentes enfocadas en la prevenci\u00f3n m\u00e9dica y la detecci\u00f3n temprana de riesgos sanitarios para las y los infantes de la demarcaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La importancia de esta obra radica en la reorganizaci\u00f3n interna del centro, el cual cuenta con \u00e1reas educativas, formativas y de cuidado especialmente acondicionadas para que el personal docente, administrativo y operativo brinde sus servicios de manera eficiente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La distribuci\u00f3n y el equipamiento de estos espacios permiten responder con sensibilidad al dinamismo de la colonia, ofrece un entorno seguro para los juegos, el aprendizaje temprano, la convivencia y la seguridad emocional de las y los menores, al tiempo que se consolidan como un pilar de confianza para las madres, padres y personas cuidadoras que trabajan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada institucional sirvi\u00f3 adem\u00e1s como marco para la clausura formal del ciclo escolar de los menores inscritos en el CECI, realiz\u00e1ndose de manera complementaria la ceremonia c\u00edvica de cambio de escolta, donde se reconoci\u00f3 la disciplina y el desarrollo formativo de la comunidad escolar que concluy\u00f3 su encomienda pedag\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 3 Juan Ignacio Corro&nbsp; Tlalnepantla, Estado de M\u00e9xico, a 15 de julio de 2026 El Presidente Municipal de Tlalnepantla, Raciel P\u00e9rez Cruz, encabez\u00f3 la entrega de las instalaciones renovadas y la develaci\u00f3n de la placa conmemorativa de la reapertura del Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calcuta\u201d, el cual estrena sede [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8,68,56],"tags":[526],"class_list":["post-21480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edomex","category-seguridad","category-tlalnepantla","tag-edomex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0 - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0 - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 3 Juan Ignacio Corro&nbsp; Tlalnepantla, Estado de M\u00e9xico, a 15 de julio de 2026 El Presidente Municipal de Tlalnepantla, Raciel P\u00e9rez Cruz, encabez\u00f3 la entrega de las instalaciones renovadas y la develaci\u00f3n de la placa conmemorativa de la reapertura del Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calcuta\u201d, el cual estrena sede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jcorroherrera\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T16:11:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T16:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Corro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Juan Ignacio Corro Herrera\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Corro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/\"},\"author\":{\"name\":\"Nacho Corro\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\"},\"headline\":\"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0\",\"datePublished\":\"2026-07-15T16:11:42+00:00\",\"dateModified\":\"2026-07-15T16:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/\"},\"wordCount\":494,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg\",\"keywords\":[\"Edomex\"],\"articleSection\":[\"Edomex\",\"Seguridad\",\"Tlalnepantla\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/\",\"name\":\"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0 - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg\",\"datePublished\":\"2026-07-15T16:11:42+00:00\",\"dateModified\":\"2026-07-15T16:11:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\",\"name\":\"Nacho Corro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"caption\":\"Nacho Corro\"},\"description\":\"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jcorroherrera\\\/\",\"www.instagram.com\\\/nachocorro\\\/\",\"https:\\\/\\\/x.com\\\/Juan Ignacio Corro Herrera\"],\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/i-corro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0 - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0 - Agencia252","og_description":"Visitas: 3 Juan Ignacio Corro&nbsp; Tlalnepantla, Estado de M\u00e9xico, a 15 de julio de 2026 El Presidente Municipal de Tlalnepantla, Raciel P\u00e9rez Cruz, encabez\u00f3 la entrega de las instalaciones renovadas y la develaci\u00f3n de la placa conmemorativa de la reapertura del Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calcuta\u201d, el cual estrena sede [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_author":"https:\/\/www.facebook.com\/jcorroherrera\/","article_published_time":"2026-07-15T16:11:42+00:00","article_modified_time":"2026-07-15T16:11:51+00:00","og_image":[{"width":1600,"height":1066,"url":"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg","type":"image\/jpeg"}],"author":"Nacho Corro","twitter_card":"summary_large_image","twitter_creator":"@Juan Ignacio Corro Herrera","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"Nacho Corro","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/"},"author":{"name":"Nacho Corro","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098"},"headline":"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0","datePublished":"2026-07-15T16:11:42+00:00","dateModified":"2026-07-15T16:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/"},"wordCount":494,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg","keywords":["Edomex"],"articleSection":["Edomex","Seguridad","Tlalnepantla"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/","url":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/","name":"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0 - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg","datePublished":"2026-07-15T16:11:42+00:00","dateModified":"2026-07-15T16:11:51+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#primaryimage","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-3.23.37-PM.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/reabren-el-centro-de-educacion-y-cuidado-infantil-madre-teresa-de-calculta-en-la-colonia-prensa-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Reabren el Centro de Educaci\u00f3n y Cuidado Infantil \u201cMadre Teresa de Calculta, en la colonia Prensa Nacional\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098","name":"Nacho Corro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","caption":"Nacho Corro"},"description":"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda","sameAs":["https:\/\/www.facebook.com\/jcorroherrera\/","www.instagram.com\/nachocorro\/","https:\/\/x.com\/Juan Ignacio Corro Herrera"],"url":"https:\/\/agencia.252.com.mx\/home\/author\/i-corro\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/21480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=21480"}],"version-history":[{"count":2,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/21480\/revisions"}],"predecessor-version":[{"id":21483,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/21480\/revisions\/21483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media\/21481"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=21480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=21480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=21480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}