{"id":19932,"date":"2026-05-28T19:21:26","date_gmt":"2026-05-29T01:21:26","guid":{"rendered":"https:\/\/agencia.252.com.mx\/home\/?p=19932"},"modified":"2026-05-28T19:35:14","modified_gmt":"2026-05-29T01:35:14","slug":"posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/","title":{"rendered":"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro"},"content":{"rendered":"<p>Visitas: 21<\/p>\n<ul class=\"wp-block-list\">\n<li><em>Bertha Alcalde Luj\u00e1n reporta aumento en judicializaciones, \u00f3rdenes de aprehensi\u00f3n y acuerdos reparatorios durante 2026<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Ignacio Corro<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Ecatepec, Estado de M\u00e9xico, a 28 de mayo de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fiscal general, Bertha Alcalde Luj\u00e1n, ratific\u00f3 que la denuncia por secuestro que present\u00f3 el Senador Javier Corral en contra de la gobernadora de Chihuahua, Maru Campos, fue cerrada por que \u201cno hay delitos que perseguir\u201d; sin embargo, considero la viabilidad que se pueda reabrir por que un juez ordeno su revisi\u00f3n ante una impugnaci\u00f3n presentada por el propio Senador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que el senador Javier Corral impugn\u00f3 la decisi\u00f3n, como lo permite el C\u00f3digo Nacional de Procedimientos Penales, lo que deriv\u00f3 en una audiencia convocada por el Tribunal Superior de Justicia de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta fiscal\u00eda es objetiva y esta fiscal\u00eda, m\u00e1s all\u00e1 de&nbsp;si un denunciante o una v\u00edctima es de determinado c\u00edrculo pol\u00edtico, va a&nbsp;actuar con toda objetividad\u201d, enfatiz\u00f3 Alcalde Luj\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Bertha Alcalde precis\u00f3 que la audiencia no fue promovida por la Fiscal\u00eda, sino por el Tribunal, que cit\u00f3 a las partes involucradas para revisar la impugnaci\u00f3n presentada por el denunciante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consider\u00f3 que la gobernadora&nbsp;&nbsp;manipul\u00f3 la informaci\u00f3n&nbsp;desde un inicio&nbsp;para \u00abotro tipo de objetivos\u201d, declar\u00f3 la funcionaria al explicar que,&nbsp;tras realizar las investigaciones, el Ministerio P\u00fablico&nbsp;concluy\u00f3 que no hab\u00eda elementos suficientes&nbsp;para&nbsp;configurar el delito de privaci\u00f3n ilegal&nbsp;de la libertad&nbsp;ni otros il\u00edcitos se\u00f1alados en la denuncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rinde informe mensual denominado \u201cTransformaci\u00f3n y Resultados\u201d<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de las acciones impulsadas en coordinaci\u00f3n con el Gabinete de Seguridad de la Ciudad de M\u00e9xico, la capital registr\u00f3 una reducci\u00f3n de 13% en delitos de alto impacto y de 12% en delitos de bajo impacto entre enero y abril de 2026, en comparaci\u00f3n con el mismo periodo de 2024.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-medium\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual--300x200.jpg\" alt=\"\" class=\"wp-image-19934\" srcset=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual--300x200.jpg 300w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual--1024x683.jpg 1024w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual--768x512.jpg 768w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual--1536x1024.jpg 1536w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual--2048x1366.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, la instituci\u00f3n report\u00f3 un incremento de 21.6% en el cumplimiento de \u00f3rdenes de aprehensi\u00f3n respecto al mismo periodo de 2024, al pasar de mil 989 a 2 mil 419 mandamientos judiciales ejecutados. En comparaci\u00f3n con 2025, el aumento fue de 9.3%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fiscal general Bertha Alcalde Luj\u00e1n destac\u00f3 que estos resultados reflejan el fortalecimiento de las investigaciones desarrolladas por las fiscal\u00edas territoriales y especializadas: \u201cLas judicializaciones se traducen en menos impunidad. Estamos impulsando investigaciones m\u00e1s s\u00f3lidas y dando seguimiento puntual a los resultados que obtiene cada \u00e1rea de la instituci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En delitos prioritarios contemplados dentro del Plan de Pol\u00edtica Criminal 2026 tambi\u00e9n se registraron incrementos en detenciones y judicializaciones: en comparaci\u00f3n con el primer cuatrimestre de 2024, el robo de veh\u00edculo registr\u00f3 un aumento de 43%; la extorsi\u00f3n, de 40%; la violaci\u00f3n, de 25%; el feminicidio, de 18%; y el homicidio doloso, de 13%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fiscal general tambi\u00e9n report\u00f3 avances en mecanismos alternativos de soluci\u00f3n de controversias y judicializaciones sin detenido. Entre enero y abril de 2026, los acuerdos reparatorios aumentaron 215% respecto al mismo periodo de 2025, al pasar de un promedio diario de 5.1 a 16.1 acuerdos celebrados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 21 Juan Ignacio Corro Ecatepec, Estado de M\u00e9xico, a 28 de mayo de 2026 La fiscal general, Bertha Alcalde Luj\u00e1n, ratific\u00f3 que la denuncia por secuestro que present\u00f3 el Senador Javier Corral en contra de la gobernadora de Chihuahua, Maru Campos, fue cerrada por que \u201cno hay delitos que perseguir\u201d; sin embargo, considero la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":19933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[69,512,458,68],"tags":[535],"class_list":["post-19932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cdmx","category-metropoli","category-nacional","category-seguridad","tag-cdmx"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 21 Juan Ignacio Corro Ecatepec, Estado de M\u00e9xico, a 28 de mayo de 2026 La fiscal general, Bertha Alcalde Luj\u00e1n, ratific\u00f3 que la denuncia por secuestro que present\u00f3 el Senador Javier Corral en contra de la gobernadora de Chihuahua, Maru Campos, fue cerrada por que \u201cno hay delitos que perseguir\u201d; sin embargo, considero la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jcorroherrera\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T01:21:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T01:35:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Corro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Juan Ignacio Corro Herrera\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Corro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/\"},\"author\":{\"name\":\"Nacho Corro\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\"},\"headline\":\"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro\",\"datePublished\":\"2026-05-29T01:21:26+00:00\",\"dateModified\":\"2026-05-29T01:35:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Informe-Mensual-2-scaled.jpg\",\"keywords\":[\"CDMX\"],\"articleSection\":[\"CDMX\",\"Metropoli\",\"Nacional\",\"Seguridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/\",\"name\":\"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Informe-Mensual-2-scaled.jpg\",\"datePublished\":\"2026-05-29T01:21:26+00:00\",\"dateModified\":\"2026-05-29T01:35:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Informe-Mensual-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Informe-Mensual-2-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\",\"name\":\"Nacho Corro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"caption\":\"Nacho Corro\"},\"description\":\"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jcorroherrera\\\/\",\"www.instagram.com\\\/nachocorro\\\/\",\"https:\\\/\\\/x.com\\\/Juan Ignacio Corro Herrera\"],\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/i-corro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/","og_locale":"es_ES","og_type":"article","og_title":"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro - Agencia252","og_description":"Visitas: 21 Juan Ignacio Corro Ecatepec, Estado de M\u00e9xico, a 28 de mayo de 2026 La fiscal general, Bertha Alcalde Luj\u00e1n, ratific\u00f3 que la denuncia por secuestro que present\u00f3 el Senador Javier Corral en contra de la gobernadora de Chihuahua, Maru Campos, fue cerrada por que \u201cno hay delitos que perseguir\u201d; sin embargo, considero la [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_author":"https:\/\/www.facebook.com\/jcorroherrera\/","article_published_time":"2026-05-29T01:21:26+00:00","article_modified_time":"2026-05-29T01:35:14+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual-2-scaled.jpg","type":"image\/jpeg"}],"author":"Nacho Corro","twitter_card":"summary_large_image","twitter_creator":"@Juan Ignacio Corro Herrera","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"Nacho Corro","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/"},"author":{"name":"Nacho Corro","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098"},"headline":"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro","datePublished":"2026-05-29T01:21:26+00:00","dateModified":"2026-05-29T01:35:14+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual-2-scaled.jpg","keywords":["CDMX"],"articleSection":["CDMX","Metropoli","Nacional","Seguridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/","url":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/","name":"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual-2-scaled.jpg","datePublished":"2026-05-29T01:21:26+00:00","dateModified":"2026-05-29T01:35:14+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#primaryimage","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual-2-scaled.jpg","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/Informe-Mensual-2-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/posible-reapertura-la-denuncia-de-javier-corral-contra-maru-campos-por-secuestro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Posible reapertura de la denuncia de Javier Corral contra Maru Campos, por secuestro"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098","name":"Nacho Corro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","caption":"Nacho Corro"},"description":"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda","sameAs":["https:\/\/www.facebook.com\/jcorroherrera\/","www.instagram.com\/nachocorro\/","https:\/\/x.com\/Juan Ignacio Corro Herrera"],"url":"https:\/\/agencia.252.com.mx\/home\/author\/i-corro\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/19932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=19932"}],"version-history":[{"count":2,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/19932\/revisions"}],"predecessor-version":[{"id":19942,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/19932\/revisions\/19942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media\/19933"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=19932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=19932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=19932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}