{"id":19899,"date":"2026-05-27T19:53:36","date_gmt":"2026-05-28T01:53:36","guid":{"rendered":"https:\/\/agencia.252.com.mx\/home\/?p=19899"},"modified":"2026-05-27T19:53:38","modified_gmt":"2026-05-28T01:53:38","slug":"pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/","title":{"rendered":"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio"},"content":{"rendered":"<p>Visitas: 30<\/p>\n<ul class=\"wp-block-list\">\n<li><em>La popularidad del futbol debe traducirse en mayor participaci\u00f3n f\u00edsica, mejores condiciones de acceso y una poblaci\u00f3n m\u00e1s saludable.<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Ignacio Corro<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Toluca, Estado de M\u00e9xico, a 27 de mayo de 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco del Mundial de Futbol 2026, la Comisi\u00f3n de Derechos Humanos del Estado de M\u00e9xico realiz\u00f3 el Congreso \u201cDerecho a la cultura f\u00edsica y la pr\u00e1ctica del deporte\u201d, con la participaci\u00f3n de especialistas, periodistas, deportistas, acad\u00e9micos y representantes de la Federaci\u00f3n Mexicana de Futbol<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la inauguraci\u00f3n, el Presidente de la CODHEM, V\u00edctor Leopoldo Delgado P\u00e9rez, destac\u00f3 que el deporte no debe entenderse \u00fanicamente como actividad recreativa o espect\u00e1culo, sino como una pr\u00e1ctica social que permite construir comunidad, fortalecer la convivencia y abrir espacios para el ejercicio efectivo de los derechos humanos, especialmente para ni\u00f1as, ni\u00f1os, adolescentes, juventudes, mujeres, personas con discapacidad y comunidades diversas.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-medium\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"211\" src=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.13-PM-300x211.jpeg\" alt=\"\" class=\"wp-image-19901\" srcset=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.13-PM-300x211.jpeg 300w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.13-PM-1024x720.jpeg 1024w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.13-PM-768x540.jpeg 768w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.13-PM-1536x1080.jpeg 1536w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.13-PM.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El titular del organismo defensor subray\u00f3 que el Mundial de Futbol 2026 representa una oportunidad para reflexionar sobre el tipo de sociedad que se desea construir alrededor del deporte, m\u00e1s all\u00e1 de la competencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que los derechos humanos tambi\u00e9n se juegan en la cancha de la vida cotidiana, ah\u00ed donde las personas participan, conviven, se reconocen y construyen comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n de Mikel Arriola Pe\u00f1aloza, Presidente Ejecutivo de la Liga BBVA MX y Comisionado Presidente de la Federaci\u00f3n Mexicana de Futbol, Jorge Antonio Romero Delgado, Director de Estrategia y Relaciones Internacionales de la Federaci\u00f3n Mexicana de Futbol, se\u00f1al\u00f3 que el futbol tiene una gran relevancia social, econ\u00f3mica y cultural en M\u00e9xico, pero advirti\u00f3 que su popularidad debe traducirse en mayor participaci\u00f3n f\u00edsica, mejores condiciones de acceso y una poblaci\u00f3n m\u00e1s saludable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Romero Delgado expuso que la cultura f\u00edsica y la pr\u00e1ctica del deporte requieren una respuesta multidimensional que involucre a gobiernos, instituciones, sociedad civil, academia e iniciativa privada. Indic\u00f3 que la soluci\u00f3n pasa por hacer el deporte m\u00e1s accesible, fortalecer su gobernanza, abrir nuevas fuentes de financiamiento y garantizar entornos seguros para ni\u00f1as, ni\u00f1os y j\u00f3venes, libres de abuso, acoso, bullying, humillaci\u00f3n y cualquier forma de violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CODHEM reiter\u00f3 que el derecho a la cultura f\u00edsica y a la pr\u00e1ctica del deporte implica mucho m\u00e1s que abrir espacios para competir: exige garantizar condiciones de acceso, seguridad, igualdad, respeto, inclusi\u00f3n y participaci\u00f3n para todas las personas. En ese sentido, el deporte debe ser una herramienta para fortalecer la salud f\u00edsica y mental, reconstruir el tejido social y promover entornos libres de discriminaci\u00f3n y violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rumbo al Mundial de Futbol 2026, el organismo defensor convoc\u00f3 a mirar este acontecimiento no solo como una fiesta deportiva, sino como una oportunidad para impulsar una agenda p\u00fablica que coloque al centro la dignidad humana, la convivencia pac\u00edfica y el derecho de todas las personas a jugar, participar, pertenecer y desarrollarse plenamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 30 Juan Ignacio Corro Toluca, Estado de M\u00e9xico, a 27 de mayo de 2026 En el marco del Mundial de Futbol 2026, la Comisi\u00f3n de Derechos Humanos del Estado de M\u00e9xico realiz\u00f3 el Congreso \u201cDerecho a la cultura f\u00edsica y la pr\u00e1ctica del deporte\u201d, con la participaci\u00f3n de especialistas, periodistas, deportistas, acad\u00e9micos y representantes [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":19900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[604,589,8,68],"tags":[526],"class_list":["post-19899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-copa-del-mundo","category-derechos-humanos","category-edomex","category-seguridad","tag-edomex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 30 Juan Ignacio Corro Toluca, Estado de M\u00e9xico, a 27 de mayo de 2026 En el marco del Mundial de Futbol 2026, la Comisi\u00f3n de Derechos Humanos del Estado de M\u00e9xico realiz\u00f3 el Congreso \u201cDerecho a la cultura f\u00edsica y la pr\u00e1ctica del deporte\u201d, con la participaci\u00f3n de especialistas, periodistas, deportistas, acad\u00e9micos y representantes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jcorroherrera\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T01:53:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T01:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Corro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Juan Ignacio Corro Herrera\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Corro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/\"},\"author\":{\"name\":\"Nacho Corro\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\"},\"headline\":\"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio\",\"datePublished\":\"2026-05-28T01:53:36+00:00\",\"dateModified\":\"2026-05-28T01:53:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg\",\"keywords\":[\"Edomex\"],\"articleSection\":[\"Copa del Mundo\",\"Derechos Humanos\",\"Edomex\",\"Seguridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/\",\"name\":\"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg\",\"datePublished\":\"2026-05-28T01:53:36+00:00\",\"dateModified\":\"2026-05-28T01:53:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg\",\"width\":1440,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\",\"name\":\"Nacho Corro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"caption\":\"Nacho Corro\"},\"description\":\"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jcorroherrera\\\/\",\"www.instagram.com\\\/nachocorro\\\/\",\"https:\\\/\\\/x.com\\\/Juan Ignacio Corro Herrera\"],\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/i-corro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/","og_locale":"es_ES","og_type":"article","og_title":"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio - Agencia252","og_description":"Visitas: 30 Juan Ignacio Corro Toluca, Estado de M\u00e9xico, a 27 de mayo de 2026 En el marco del Mundial de Futbol 2026, la Comisi\u00f3n de Derechos Humanos del Estado de M\u00e9xico realiz\u00f3 el Congreso \u201cDerecho a la cultura f\u00edsica y la pr\u00e1ctica del deporte\u201d, con la participaci\u00f3n de especialistas, periodistas, deportistas, acad\u00e9micos y representantes [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_author":"https:\/\/www.facebook.com\/jcorroherrera\/","article_published_time":"2026-05-28T01:53:36+00:00","article_modified_time":"2026-05-28T01:53:38+00:00","og_image":[{"width":1440,"height":800,"url":"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg","type":"image\/jpeg"}],"author":"Nacho Corro","twitter_card":"summary_large_image","twitter_creator":"@Juan Ignacio Corro Herrera","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"Nacho Corro","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/"},"author":{"name":"Nacho Corro","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098"},"headline":"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio","datePublished":"2026-05-28T01:53:36+00:00","dateModified":"2026-05-28T01:53:38+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg","keywords":["Edomex"],"articleSection":["Copa del Mundo","Derechos Humanos","Edomex","Seguridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/","url":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/","name":"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg","datePublished":"2026-05-28T01:53:36+00:00","dateModified":"2026-05-28T01:53:38+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#primaryimage","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-6.11.14-PM.jpeg","width":1440,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/pide-codhem-a-la-aficion-del-futbol-ver-el-deporta-como-un-derecho-no-como-un-privilegio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Pide CODHEM a la afici\u00f3n del futbol ver el deporta como un derecho, no como un privilegio"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098","name":"Nacho Corro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","caption":"Nacho Corro"},"description":"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda","sameAs":["https:\/\/www.facebook.com\/jcorroherrera\/","www.instagram.com\/nachocorro\/","https:\/\/x.com\/Juan Ignacio Corro Herrera"],"url":"https:\/\/agencia.252.com.mx\/home\/author\/i-corro\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/19899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=19899"}],"version-history":[{"count":1,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/19899\/revisions"}],"predecessor-version":[{"id":19902,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/19899\/revisions\/19902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media\/19900"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=19899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=19899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=19899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}