{"id":187,"date":"2021-09-03T19:08:00","date_gmt":"2021-09-04T00:08:00","guid":{"rendered":"http:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/"},"modified":"2021-09-03T19:08:00","modified_gmt":"2021-09-04T00:08:00","slug":"opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/","title":{"rendered":"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico"},"content":{"rendered":"<p>Visitas: 54<\/p><p>&nbsp;<\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\">\n<ul>\n<li><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">Con los descuentos se financi\u00f3 la creaci\u00f3n de Morena en 2013 y la campa\u00f1a de Delfina G\u00f3mez al Edomex.<\/span><\/li>\n<li><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">Entre los proveedores de las campa\u00f1as pol\u00edticas de Morena en 2015 est\u00e1n Luis David Miranda G\u00f3mez, Jos\u00e9 V\u00edctor Maga\u00f1a G\u00f3mez y la Comercializadora de Oriente Mavi-he<\/span><\/li>\n<li><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">El INE no puede ni debe inhibirse porque se trate del partido del gobierno.<\/span><\/li>\n<li><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">El grupo Texcoco que lidera Higinio Mart\u00ednez se tambalea de cara a la sucesi\u00f3n de 2023.<\/span><\/li>\n<\/ul>\n<div><span face=\"Arimo, sans-serif\"><span style=\"font-size: 13.3333px;\">Por: Nacho Corro<\/span><\/span><\/div>\n<\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">Desde el Ayuntamiento de Texcoco, Estado de M\u00e9xico, el partido Morena oper\u00f3 una trama ilegal de financiamiento pol\u00edtico y electoral, con lo que se coste\u00f3 la creaci\u00f3n de dicho instituto pol\u00edtico en 2015 y la campa\u00f1a al gobierno del Estado de M\u00e9xico en 2017 por la entonces candidata Delfina G\u00f3mez, hoy Secretaria de Educaci\u00f3n P\u00fablica (SEP).<o:p><\/o:p><\/span><\/p>\n<div>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">En sesi\u00f3n del Consejo General del INE, la autoridad electoral aprob\u00f3 por unanimidad sancionar con 4.5 millones de pesos al partido Morena derivado de que, en una investigaci\u00f3n en materia de fiscalizaci\u00f3n, comprob\u00f3 la retenci\u00f3n del 10 por ciento de su sueldo a 550 empleados p\u00fablicos durante dos a\u00f1os de gesti\u00f3n de la entonces alcaldesa de Texcoco Delfina G\u00f3mez.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">El modo de operaci\u00f3n de esta trama corri\u00f3 a cargo de Mar\u00eda Victoria Anaya Campos, quien gir\u00f3 cheques bajo el concepto de apoyos al llamado Grupo de Acci\u00f3n Pol\u00edtica (GAP), con la firma de la otrora Presidenta Municipal Delfina G\u00f3mez \u00c1lvarez, el s\u00edndico Eliseo Edmundo Rosales L\u00f3pez, del Secretario del Ayuntamiento, Horacio Duarte Olivares, ex representante de Morena ante el INE y actual Director de Aduanas-, as\u00ed como Alberto Mart\u00ednez Miranda, el tesorero.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\">\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/s1280\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" data-original-height=\"853\" data-original-width=\"1280\" height=\"303\" src=\"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\" width=\"456\" \/><\/a><\/div>\n<p><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\"><br \/><\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Despu\u00e9s de dos a\u00f1os de descuentos a trabajadores p\u00fablicos del municipio y del DIF Texcoco de febrero de 2013 hasta julio de 2015, el monto retenido ascendi\u00f3 a 13 millones 589 mil pesos.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Mar\u00eda Victoria Anaya tuvo un cargo de confianza en la Presidencia Municipal de Texcoco desde enero de 2013 y hasta febrero de 2015. M\u00e1s tarde fue coordinadora de giras de la campa\u00f1a electoral de Delfina G\u00f3mez cuando se postul\u00f3 para gobernadora del Estado de M\u00e9xico en 2017.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">El INE comprob\u00f3 que la retenci\u00f3n del dinero a los trabajadores se transfiri\u00f3 tambi\u00e9n a dos empleadas p\u00fablicas del mismo ayuntamiento, contratadas por la propia Presidencia Municipal y militantes del partido Morena.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Mar\u00eda Victoria Anaya deposit\u00f3 33 de los 50 cheques emitidos a su favor por el ayuntamiento en una cuenta personal por un monto de 7 millones 777 mil pesos; los dem\u00e1s cheques los cobraba ella misma en efectivo por un monto de 3 millones 594 mil.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Adem\u00e1s, el municipio le hizo una transferencia bancaria en mayo de 2015 por 368 mil pesos as\u00ed que, de acuerdo con las constancias que otorg\u00f3 la Comisi\u00f3n Nacional Bancaria y de Valores (CNBV) al Instituto, lo que recibi\u00f3 del ayuntamiento en cheques y transferencia alcanz\u00f3 11 millones 741 mil pesos.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">De ese dinero que recibi\u00f3 Mar\u00eda Victoria Anaya, se sabe que 200 mil los deposit\u00f3 a la cuenta de Morena, lo que fue sancionado por el INE al revisar el informe de 2015.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Adem\u00e1s, gir\u00f3 31 cheques a personas f\u00edsicas por un monto de 4 millones 279 mil pesos.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Tambi\u00e9n expidi\u00f3 otros cinco cheques a personas morales por un mill\u00f3n 700 mil pesos y ella se autoexpidi\u00f3 <\/span><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">cheques para cobrarlos en efectivo por un monto de un mill\u00f3n 841 mil; y dos cheques a terceros por 484 mil pesos.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Entre los destinatarios del dinero que manej\u00f3 Mar\u00eda Victoria Anaya, est\u00e1n proveedores de las campa\u00f1as pol\u00edticas de MORENA en 2015, como son Luis David Miranda G\u00f3mez, Jos\u00e9 V\u00edctor Maga\u00f1a G\u00f3mez y la Comercializadora de Oriente Mavi-he.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">&nbsp;<\/span><b><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">Dinero fue a parar al GAP, grupo pol\u00edtico que emana del PRD y luego form\u00f3 a Morena<\/span><\/b><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">El Consejero Electoral Ciro Murayama explic\u00f3 que los cheques del ayuntamiento ten\u00edan como objeto dar recursos al Grupo de Acci\u00f3n Pol\u00edtica (GAP), cuyos miembros al ser emplazados manifestaron ser una organizaci\u00f3n altruista, pero no era as\u00ed, destac\u00f3.<o:p><\/o:p><\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Subray\u00f3 que el GAP es una corriente pol\u00edtica que fue parte del Partido de la Revoluci\u00f3n Democr\u00e1tica (PRD) hasta 2011, hasta que en 2013 sus principales l\u00edderes se incorporan a la fundaci\u00f3n del partido Morena.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">El GAP, se investig\u00f3, no es una organizaci\u00f3n formalmente registrada, por lo cual \u201cllama la atenci\u00f3n de la autoridad electoral que tanto la Presidenta Municipal, el s\u00edndico, el Secretario del Ayuntamiento y el tesorero del ayuntamiento de Texcoco, emitieron cheques para un ente que carece de constituci\u00f3n legal\u201d, anot\u00f3 Murayama.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">De acuerdo con la investigaci\u00f3n realizada por el INE, los l\u00edderes del GAP son dirigentes que participaron como candidatas y candidatos a cargos electos de Morena durante tres a\u00f1os (de 2015 a 2017).<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">En esa l\u00f3gica de operaci\u00f3n se emitieron los cheques del ayuntamiento de Texcoco al Grupo de Acci\u00f3n Pol\u00edtica de manera coincidente con la formaci\u00f3n del partico Morena en 2013 para buscar su registro, as\u00ed como la obtenci\u00f3n del registro en 2014, y su primera campa\u00f1a electoral en 2015.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">\u201cPara el INE no hay duda de la imbricaci\u00f3n entre el GAP y Morena, tampoco de la actividad partidista y pol\u00edtico electoral de las personas que retuvieron los recursos a los trabajadores que emitieron los cheques desde el ayuntamiento y de quienes lo recibieron y cobraron\u201d, atiz\u00f3.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><b><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">Cobrar diezmos a los trabajadores es un abuso lo haga quien lo haga<\/span><\/b><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">La irregularidad, a\u00f1adi\u00f3 Muyarama, est\u00e1 en ordenar descontar dinero a los empleados p\u00fablicos y que se utilizaron los recursos del ayuntamiento para hacer esa retenci\u00f3n y, desde las arcas p\u00fablicas, se emitieron cheques para financiar al Grupo de Acci\u00f3n Pol\u00edtica en nombre de dos militantes de Morena, a su vez empleadas p\u00fablicas del municipio.<o:p><\/o:p><\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\">\n<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-Y18yxZpEZ50\/YTLG8-PM38I\/AAAAAAAANP4\/Oix-pQuegPo6phGomay1HNTm3heFvDejQCLcBGAsYHQ\/s1280\/murayama.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"853\" data-original-width=\"1280\" height=\"279\" src=\"https:\/\/1.bp.blogspot.com\/-Y18yxZpEZ50\/YTLG8-PM38I\/AAAAAAAANP4\/Oix-pQuegPo6phGomay1HNTm3heFvDejQCLcBGAsYHQ\/w419-h279\/murayama.jpg\" width=\"419\" \/><\/a><\/div>\n<p><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\"><br \/><\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">A partir de que se denunci\u00f3 esta trama en el debate por la gubernatura del Estado de M\u00e9xico, la propia Delfina G\u00f3mez declar\u00f3 en una entrevista que la retenci\u00f3n del dinero a los trabajadores fue para la causa del partido el presidente Andr\u00e9s Manuel L\u00f3pez Obrador.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Y opin\u00f3: \u201cLejos estaremos de una vida p\u00fablica y pol\u00edtica a salvo de corrupci\u00f3n si permitimos que el uso patrimonial de cargos p\u00fablicos quede impune\u201d.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Cobrar diezmos a los trabajadores es un abuso lo haga quien lo haga. Es pensar que el trabajador debe su empleo al partido gobernante en turno y que por eso pueden quitarle parte de su salario; descontar n\u00f3mina para financiar apuestas pol\u00edticas personales y de grupo es una conducta del subdesarrollo pol\u00edtico, propia del clientelismo<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">&nbsp;<\/span><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">El INE multa conductas ilegales con independencia de qu\u00e9 fuerza pol\u00edtica incurra en ellas.<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">&nbsp;<\/span><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">Y mand\u00f3 un mensaje al presidente L\u00f3pez Obrador:<\/span><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\"><span face=\"&quot;Arimo&quot;,sans-serif\" style=\"font-size: 10pt;\">&nbsp;<\/span><span face=\"Arimo, sans-serif\" style=\"font-size: 10pt;\">\u201cEsta autoridad fiscalizadora no puede ni debe inhibirse porque se trate del partido del gobierno, solo as\u00ed con pruebas contundentes, sin actos temerarios, pero sin temor, el INE reafirma su autonom\u00eda e independencia como \u00e1rbitro imparcial y riguroso\u201d.&nbsp;<\/span><\/p>\n<p style=\"background: white; line-height: normal; margin-bottom: 0cm; text-align: justify;\"><b>No hay v\u00ednculo ni relaci\u00f3n entre las personas f\u00edsicas y morales <o:p><\/o:p><\/b><\/p>\n<p style=\"background: white; line-height: normal; margin-bottom: 0cm; text-align: justify;\">En la defensa, Luis Eur\u00edpides Alejandro Flores Pacheco, representante de Morena ante el INE<b> aleg\u00f3 que el pro<\/b>yecto no demuestra v\u00ednculo entre las personas f\u00edsicas y morales a las cuales la persona se\u00f1alada libr\u00f3 cheques de los que supuestamente se benefici\u00f3 en \u00faltima instancia a Morena.<b><o:p><\/o:p><\/b><\/p>\n<p style=\"background: white; line-height: normal; margin-bottom: 0cm; text-align: justify;\"><b>&nbsp;<\/b><span style=\"background-color: transparent;\">Explic\u00f3 que la sanci\u00f3n pretendida no se relaciona con el monto involucrado de dos millones, y que \u201chablar de 14 millones parte de la premisa err\u00f3nea de considerar que dos personas f\u00edsicas, as\u00ed como otra persona moral, tienen relaci\u00f3n con Morena, esto porque de conformidad con la autoridad, estas mismas personas est\u00e1n registradas como proveedores de Morena ante el Sistema Integral de Fiscalizaci\u00f3n\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><o:p><\/o:p><\/p>\n<p style=\"text-align: justify;\">Sin embargo, dijo, hay una deducci\u00f3n que no es l\u00f3gica, ya que esta autoridad est\u00e1 partiendo de una interpretaci\u00f3n o una premisa err\u00f3nea. <o:p><\/o:p><\/p>\n<p style=\"text-align: justify;\">\u201cUna cosa es que exista el registro de proveedores de personas f\u00edsicas y morales, que ya mencionamos; y otra cosa es que haya beneficiado a Morena con los supuestos cheques que se libraron a nombre de estas personas. <o:p><\/o:p><\/p>\n<p style=\"line-height: normal; margin-bottom: 0cm; text-align: justify;\">\n<p style=\"text-align: justify;\">As\u00ed, la relaci\u00f3n y conclusi\u00f3n que pretende construir esta autoridad administrativa electoral no es algo evidente y ni siquiera indiciario, porque si Morena los ha registrado como proveedores, no se demuestra en el proyecto operaci\u00f3n alguna que mi representada haya celebrado con las personas referidas para efectos espec\u00edficamente de la utilizaci\u00f3n del monto involucrado en el sostenimiento de actividades de este Instituto.&nbsp;<o:p><\/o:p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 54&nbsp; Con los descuentos se financi\u00f3 la creaci\u00f3n de Morena en 2013 y la campa\u00f1a de Delfina G\u00f3mez al Edomex. Entre los proveedores de las campa\u00f1as pol\u00edticas de Morena en 2015 est\u00e1n Luis David Miranda G\u00f3mez, Jos\u00e9 V\u00edctor Maga\u00f1a G\u00f3mez y la Comercializadora de Oriente Mavi-he El INE no puede ni debe inhibirse porque [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8,119,121,123],"tags":[],"class_list":["post-187","post","type-post","status-publish","format-standard","hentry","category-edomex","category-ine","category-morena","category-texcoco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 54&nbsp; Con los descuentos se financi\u00f3 la creaci\u00f3n de Morena en 2013 y la campa\u00f1a de Delfina G\u00f3mez al Edomex. Entre los proveedores de las campa\u00f1as pol\u00edticas de Morena en 2015 est\u00e1n Luis David Miranda G\u00f3mez, Jos\u00e9 V\u00edctor Maga\u00f1a G\u00f3mez y la Comercializadora de Oriente Mavi-he El INE no puede ni debe inhibirse porque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-04T00:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\" \/>\n<meta name=\"author\" content=\"AGN252\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@252coms\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AGN252\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/\"},\"author\":{\"name\":\"AGN252\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/d5e8a32cbe0a109de6d937630ff2de33\"},\"headline\":\"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico\",\"datePublished\":\"2021-09-04T00:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/\"},\"wordCount\":1487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-slKmpTUnOrU\\\/YTLG2nhtvmI\\\/AAAAAAAANP0\\\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\\\/w456-h303\\\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\",\"articleSection\":[\"Edomex\",\"INE\",\"Morena\",\"Texcoco\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/\",\"name\":\"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-slKmpTUnOrU\\\/YTLG2nhtvmI\\\/AAAAAAAANP0\\\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\\\/w456-h303\\\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\",\"datePublished\":\"2021-09-04T00:08:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-slKmpTUnOrU\\\/YTLG2nhtvmI\\\/AAAAAAAANP0\\\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\\\/w456-h303\\\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\",\"contentUrl\":\"https:\\\/\\\/1.bp.blogspot.com\\\/-slKmpTUnOrU\\\/YTLG2nhtvmI\\\/AAAAAAAANP0\\\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\\\/w456-h303\\\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/d5e8a32cbe0a109de6d937630ff2de33\",\"name\":\"AGN252\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2ce5e5e79fca34278d1b7be0f97339a8e5ab0638f784d893e037a0ef26dc0c8?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2ce5e5e79fca34278d1b7be0f97339a8e5ab0638f784d893e037a0ef26dc0c8?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2ce5e5e79fca34278d1b7be0f97339a8e5ab0638f784d893e037a0ef26dc0c8?s=96&r=g\",\"caption\":\"AGN252\"},\"sameAs\":[\"http:\\\/\\\/agencia.252.com.mx\",\"https:\\\/\\\/x.com\\\/252coms\"],\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico - Agencia252","og_description":"Visitas: 54&nbsp; Con los descuentos se financi\u00f3 la creaci\u00f3n de Morena en 2013 y la campa\u00f1a de Delfina G\u00f3mez al Edomex. Entre los proveedores de las campa\u00f1as pol\u00edticas de Morena en 2015 est\u00e1n Luis David Miranda G\u00f3mez, Jos\u00e9 V\u00edctor Maga\u00f1a G\u00f3mez y la Comercializadora de Oriente Mavi-he El INE no puede ni debe inhibirse porque [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_published_time":"2021-09-04T00:08:00+00:00","og_image":[{"url":"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg","type":"","width":"","height":""}],"author":"AGN252","twitter_card":"summary_large_image","twitter_creator":"@252coms","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"AGN252","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/"},"author":{"name":"AGN252","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/d5e8a32cbe0a109de6d937630ff2de33"},"headline":"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico","datePublished":"2021-09-04T00:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/"},"wordCount":1487,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg","articleSection":["Edomex","INE","Morena","Texcoco"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/","url":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/","name":"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg","datePublished":"2021-09-04T00:08:00+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#primaryimage","url":"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg","contentUrl":"https:\/\/1.bp.blogspot.com\/-slKmpTUnOrU\/YTLG2nhtvmI\/AAAAAAAANP0\/Bxjxwl1HlnAR5IFMYRjajNyvErBlZaMXACLcBGAsYHQ\/w456-h303\/9283bc41-f334-42af-b03a-23626afc7e9b.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/opero-morena-una-trama-ilegal-para-financiar-la-campana-de-delfina-gomez-a-la-gubernatura-del-estado-de-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Oper\u00f3 Morena una trama ilegal para financiar la campa\u00f1a de Delfina G\u00f3mez a la gubernatura del Estado de M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/d5e8a32cbe0a109de6d937630ff2de33","name":"AGN252","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d2ce5e5e79fca34278d1b7be0f97339a8e5ab0638f784d893e037a0ef26dc0c8?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2ce5e5e79fca34278d1b7be0f97339a8e5ab0638f784d893e037a0ef26dc0c8?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2ce5e5e79fca34278d1b7be0f97339a8e5ab0638f784d893e037a0ef26dc0c8?s=96&r=g","caption":"AGN252"},"sameAs":["http:\/\/agencia.252.com.mx","https:\/\/x.com\/252coms"],"url":"https:\/\/agencia.252.com.mx\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=187"}],"version-history":[{"count":0,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/187\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}