{"id":14032,"date":"2025-12-18T20:51:38","date_gmt":"2025-12-19T02:51:38","guid":{"rendered":"https:\/\/agencia.252.com.mx\/home\/?p=14032"},"modified":"2025-12-18T21:15:14","modified_gmt":"2025-12-19T03:15:14","slug":"tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores","status":"publish","type":"post","link":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/","title":{"rendered":"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0"},"content":{"rendered":"<p>Visitas: 34<\/p>\n<ul class=\"wp-block-list\">\n<li><em>Un polic\u00eda de la capital resulto<\/em> lesionado en la operaci\u00f3n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Ignacio Corro<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Ciudad de M\u00e9xico, 18 de diciembre de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anoche la denuncia por extorsi\u00f3n de una empresa de paqueter\u00eda ubicada en la Colonia Cuauht\u00e9moc moviliz\u00f3 esta ma\u00f1ana a distintas corporaciones de la Secretar\u00eda de Seguridad P\u00fablica de la Ciudad de M\u00e9xico para detener a los delincuentes; en la operaci\u00f3n y, tras una intensa balacera, seis personas fueron detenidas<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-medium\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-2-300x169.jpeg\" alt=\"\" class=\"wp-image-14035\" srcset=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-2-300x169.jpeg 300w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-2-1024x576.jpeg 1024w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-2-768x432.jpeg 768w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-2-1536x864.jpeg 1536w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-2.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de una llamada telef\u00f3nica al \u00e1rea especializada de combate al delito de extorsi\u00f3n, personal de la Secretar\u00eda de Seguridad Ciudadana (SSC) de la Ciudad de M\u00e9xico atendi\u00f3 la denuncia, tom\u00f3 conocimiento de un grupo de sujetos que amenazaron a los trabajadores y propietarios de una empresa de paqueter\u00eda localizada en la calle R\u00edo Ebro, de la colonia Cuauht\u00e9moc, en la alcald\u00eda del mismo nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue as\u00ed que se establecieron vigilancias fijas, m\u00f3viles y discretas en la zona para proteger a las posibles v\u00edctimas e identificar a los probables responsables que, de acuerdo con los trabajos de inteligencia, acudir\u00edan al lugar y, con esto desarrollar la investigaci\u00f3n del caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, durante la vigilancia se detect\u00f3 que los presuntos extorsionadores arribaron armados y ante la inminente situaci\u00f3n de riesgo, los polic\u00edas decidieron intervenir para su detenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese momento, uno de los presuntos responsables comenz\u00f3 a realizar disparos en su contra por lo que, al ver en riesgo su vida y la de las dem\u00e1s personas en el sitio, repelieron la agresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de controlar la situaci\u00f3n y con el apoyo de otros equipos de trabajo y el sobrevuelo de una unidad de los C\u00f3ndores, cuatro hombres de 30, 35, 36 y 54 a\u00f1os de edad fueron detenidos, informados de sus derechos de ley y puestos a disposici\u00f3n del agente del Ministerio P\u00fablico correspondiente quien definir\u00e1 su situaci\u00f3n jur\u00eddica. Adem\u00e1s, se contin\u00faa con la atenci\u00f3n a los denunciantes para la integraci\u00f3n de la carpeta de investigaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-medium\"><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-1-225x300.jpeg\" alt=\"\" class=\"wp-image-14034\" srcset=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-1-225x300.jpeg 225w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-1-768x1024.jpeg 768w, https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44-1.jpeg 960w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Derivado de las acciones, un polic\u00eda result\u00f3 lesionado en la cavidad abdominal, por lo que r\u00e1pidamente fue llevado a un hospital para su atenci\u00f3n m\u00e9dica especializada, donde se reporta estable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe mencionar que, dos personas m\u00e1s fueron detenidas minutos despu\u00e9s, las cuales tambi\u00e9n fueron trasladadas a la autoridad ministerial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Ciudad de M\u00e9xico la extorsi\u00f3n no tiene cabida ni espacio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un mensaje en su cuenta de X, el Secretario de Seguridad P\u00fablica, Pablo V\u00e1zquez Camacho destac\u00f3 la acci\u00f3n de los elementos en contra extorsionadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSu trabajo, compromiso y valent\u00eda son fundamentales para proteger a las y los habitantes de la capital. Me mantengo pendiente a la salud del polic\u00eda que sali\u00f3 lesionado\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitas: 34 Juan Ignacio Corro Ciudad de M\u00e9xico, 18 de diciembre de 2025 Anoche la denuncia por extorsi\u00f3n de una empresa de paqueter\u00eda ubicada en la Colonia Cuauht\u00e9moc moviliz\u00f3 esta ma\u00f1ana a distintas corporaciones de la Secretar\u00eda de Seguridad P\u00fablica de la Ciudad de M\u00e9xico para detener a los delincuentes; en la operaci\u00f3n y, tras [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":14033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[69,68],"tags":[526,506],"class_list":["post-14032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cdmx","category-seguridad","tag-edomex","tag-seguridad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0 - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0 - Agencia252\" \/>\n<meta property=\"og:description\" content=\"Visitas: 34 Juan Ignacio Corro Ciudad de M\u00e9xico, 18 de diciembre de 2025 Anoche la denuncia por extorsi\u00f3n de una empresa de paqueter\u00eda ubicada en la Colonia Cuauht\u00e9moc moviliz\u00f3 esta ma\u00f1ana a distintas corporaciones de la Secretar\u00eda de Seguridad P\u00fablica de la Ciudad de M\u00e9xico para detener a los delincuentes; en la operaci\u00f3n y, tras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/252Comunicacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jcorroherrera\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T02:51:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T03:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"902\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Corro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Juan Ignacio Corro Herrera\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Corro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/\"},\"author\":{\"name\":\"Nacho Corro\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\"},\"headline\":\"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0\",\"datePublished\":\"2025-12-19T02:51:38+00:00\",\"dateModified\":\"2025-12-19T03:15:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg\",\"keywords\":[\"Edomex\",\"Seguridad\"],\"articleSection\":[\"CDMX\",\"Seguridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/\",\"name\":\"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0 - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg\",\"datePublished\":\"2025-12-19T02:51:38+00:00\",\"dateModified\":\"2025-12-19T03:15:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg\",\"width\":1600,\"height\":902},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/person\\\/6b972021e9a92d45ade8c78d81509098\",\"name\":\"Nacho Corro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g\",\"caption\":\"Nacho Corro\"},\"description\":\"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jcorroherrera\\\/\",\"www.instagram.com\\\/nachocorro\\\/\",\"https:\\\/\\\/x.com\\\/Juan Ignacio Corro Herrera\"],\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/author\\\/i-corro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0 - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/","og_locale":"es_ES","og_type":"article","og_title":"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0 - Agencia252","og_description":"Visitas: 34 Juan Ignacio Corro Ciudad de M\u00e9xico, 18 de diciembre de 2025 Anoche la denuncia por extorsi\u00f3n de una empresa de paqueter\u00eda ubicada en la Colonia Cuauht\u00e9moc moviliz\u00f3 esta ma\u00f1ana a distintas corporaciones de la Secretar\u00eda de Seguridad P\u00fablica de la Ciudad de M\u00e9xico para detener a los delincuentes; en la operaci\u00f3n y, tras [&hellip;]","og_url":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/","og_site_name":"Agencia252","article_publisher":"https:\/\/www.facebook.com\/252Comunicacion\/","article_author":"https:\/\/www.facebook.com\/jcorroherrera\/","article_published_time":"2025-12-19T02:51:38+00:00","article_modified_time":"2025-12-19T03:15:14+00:00","og_image":[{"width":1600,"height":902,"url":"http:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg","type":"image\/jpeg"}],"author":"Nacho Corro","twitter_card":"summary_large_image","twitter_creator":"@Juan Ignacio Corro Herrera","twitter_site":"@252COMS","twitter_misc":{"Escrito por":"Nacho Corro","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#article","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/"},"author":{"name":"Nacho Corro","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098"},"headline":"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0","datePublished":"2025-12-19T02:51:38+00:00","dateModified":"2025-12-19T03:15:14+00:00","mainEntityOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg","keywords":["Edomex","Seguridad"],"articleSection":["CDMX","Seguridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/","url":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/","name":"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0 - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#primaryimage"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#primaryimage"},"thumbnailUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg","datePublished":"2025-12-19T02:51:38+00:00","dateModified":"2025-12-19T03:15:14+00:00","breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#primaryimage","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-18-at-20.45.44.jpeg","width":1600,"height":902},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/tras-intensa-balacera-en-la-cdmx-son-detenidos-seis-extorsionadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Tras intensa balacera en la CDMX, son detenidos seis extorsionadores\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]},{"@type":"Person","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/person\/6b972021e9a92d45ade8c78d81509098","name":"Nacho Corro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5db6df507cfe1307e192fbb498c6b85f1cf2ffd8b4cd37141b9eea588fcbd5a4?s=96&r=g","caption":"Nacho Corro"},"description":"Comunicador Social, Periodista y Administraci\u00f3n P\u00fablica. Conversador pol\u00edtico, temas electorales y seguridad. Generador de contenidos digitales. Amante de la fotograf\u00eda","sameAs":["https:\/\/www.facebook.com\/jcorroherrera\/","www.instagram.com\/nachocorro\/","https:\/\/x.com\/Juan Ignacio Corro Herrera"],"url":"https:\/\/agencia.252.com.mx\/home\/author\/i-corro\/"}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/14032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/comments?post=14032"}],"version-history":[{"count":1,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/14032\/revisions"}],"predecessor-version":[{"id":14036,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts\/14032\/revisions\/14036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media\/14033"}],"wp:attachment":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/media?parent=14032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories?post=14032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/tags?post=14032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}