{"id":299,"count":11,"description":"","link":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/","name":"Chimalhuac\u00e1n","slug":"chimalhuacan","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chimalhuac\u00e1n archivos - Agencia252<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chimalhuac\u00e1n archivos - Agencia252\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/\" \/>\n<meta property=\"og:site_name\" content=\"Agencia252\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@252COMS\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/category\\\/chimalhuacan\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/category\\\/chimalhuacan\\\/\",\"name\":\"Chimalhuac\u00e1n archivos - Agencia252\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/category\\\/chimalhuacan\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/category\\\/chimalhuacan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chimalhuac\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"name\":\"Agencia252\",\"description\":\"Tu espacio en la Red\",\"publisher\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#organization\",\"name\":\"Agencia252\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"contentUrl\":\"https:\\\/\\\/agencia.252.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/cropped-ciruclo-agencia-e1677562404136.png\",\"width\":512,\"height\":512,\"caption\":\"Agencia252\"},\"image\":{\"@id\":\"https:\\\/\\\/agencia.252.com.mx\\\/home\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/252Comunicacion\\\/\",\"https:\\\/\\\/x.com\\\/252COMS\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chimalhuac\u00e1n archivos - Agencia252","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/","og_locale":"es_ES","og_type":"article","og_title":"Chimalhuac\u00e1n archivos - Agencia252","og_url":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/","og_site_name":"Agencia252","og_image":[{"width":512,"height":512,"url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@252COMS","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/","url":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/","name":"Chimalhuac\u00e1n archivos - Agencia252","isPartOf":{"@id":"https:\/\/agencia.252.com.mx\/home\/#website"},"breadcrumb":{"@id":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/agencia.252.com.mx\/home\/category\/chimalhuacan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agencia.252.com.mx\/home\/"},{"@type":"ListItem","position":2,"name":"Chimalhuac\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/agencia.252.com.mx\/home\/#website","url":"https:\/\/agencia.252.com.mx\/home\/","name":"Agencia252","description":"Tu espacio en la Red","publisher":{"@id":"https:\/\/agencia.252.com.mx\/home\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agencia.252.com.mx\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agencia.252.com.mx\/home\/#organization","name":"Agencia252","url":"https:\/\/agencia.252.com.mx\/home\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/","url":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","contentUrl":"https:\/\/agencia.252.com.mx\/wp-content\/uploads\/2023\/02\/cropped-ciruclo-agencia-e1677562404136.png","width":512,"height":512,"caption":"Agencia252"},"image":{"@id":"https:\/\/agencia.252.com.mx\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/252Comunicacion\/","https:\/\/x.com\/252COMS"]}]}},"_links":{"self":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/agencia.252.com.mx\/home\/wp-json\/wp\/v2\/posts?categories=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}